{"id":6606,"date":"2018-10-25T18:25:43","date_gmt":"2018-10-25T16:25:43","guid":{"rendered":"https:\/\/www.sos-massage.ch\/fr\/?page_id=6606"},"modified":"2018-11-10T17:53:37","modified_gmt":"2018-11-10T16:53:37","slug":"impresum-2","status":"publish","type":"page","link":"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/","title":{"rendered":"Protection des donn\u00e9es et informations l\u00e9gales"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime;][et_pb_fullwidth_header title=\u00a0\u00bbProtection des donn\u00e9es et informations l\u00e9gales\u00a0\u00bb _builder_version=\u00a0\u00bb3.17.2&Prime; title_text_color=\u00a0\u00bb#cc0000&Prime; title_font_size=\u00a0\u00bb38px\u00a0\u00bb title_font_size_tablet=\u00a0\u00bb28px\u00a0\u00bb title_font_size_phone=\u00a0\u00bb25px\u00a0\u00bb title_font_size_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb content_font_size=\u00a0\u00bb18px\u00a0\u00bb background_color=\u00a0\u00bb#dedede\u00a0\u00bb background_layout=\u00a0\u00bblight\u00a0\u00bb max_width_tablet=\u00a0\u00bb50px\u00a0\u00bb button_one_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_size__hover=\u00a0\u00bbnull\u00a0\u00bb button_two_text_size__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_size__hover=\u00a0\u00bbnull\u00a0\u00bb button_one_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_text_color__hover=\u00a0\u00bbnull\u00a0\u00bb button_two_text_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_text_color__hover=\u00a0\u00bbnull\u00a0\u00bb button_one_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_width__hover=\u00a0\u00bbnull\u00a0\u00bb button_two_border_width__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_width__hover=\u00a0\u00bbnull\u00a0\u00bb button_one_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_color__hover=\u00a0\u00bbnull\u00a0\u00bb button_two_border_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_color__hover=\u00a0\u00bbnull\u00a0\u00bb button_one_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_border_radius__hover=\u00a0\u00bbnull\u00a0\u00bb button_two_border_radius__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_border_radius__hover=\u00a0\u00bbnull\u00a0\u00bb button_one_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_letter_spacing__hover=\u00a0\u00bbnull\u00a0\u00bb button_two_letter_spacing__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_letter_spacing__hover=\u00a0\u00bbnull\u00a0\u00bb button_one_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_one_bg_color__hover=\u00a0\u00bbnull\u00a0\u00bb button_two_bg_color__hover_enabled=\u00a0\u00bboff\u00a0\u00bb button_two_bg_color__hover=\u00a0\u00bbnull\u00a0\u00bb]<br \/>\n[\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime;][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb3.0.47&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.0.47&Prime; parallax=\u00a0\u00bboff\u00a0\u00bb parallax_method=\u00a0\u00bbon\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb3.17.2&Prime; text_font_size=\u00a0\u00bb16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb text_orientation=\u00a0\u00bbjustified\u00a0\u00bb]<\/p>\n<h5>1. Protection des donn\u00e9es<\/h5>\n<p>Nous accordons une grande importance \u00e0 la protection de vos donn\u00e9es personnelles. Nous les traitons donc avec le plus grand soin, conform\u00e9ment aux dispositions l\u00e9gales en vigueur relatives \u00e0 la protection des donn\u00e9es et \u00e0 la d\u00e9claration de confidentialit\u00e9.<\/p>\n<p>Dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9, nous vous informons sur nos m\u00e9thodes de traitement des donn\u00e9es. Nous vous expliquons quelles donn\u00e9es nous traitons lors de l&rsquo;acc\u00e8s \u00e0 notre pr\u00e9sence num\u00e9rique.<\/p>\n<h5>2. Quelles sont les donn\u00e9es recueillies?<\/h5>\n<p>En principe, notre pr\u00e9sence num\u00e9rique peut \u00eatre utilis\u00e9e sans que vous ayez \u00e0 fournir de donn\u00e9es personnelles. Selon la pratique courante, certaines donn\u00e9es telles que les adresses IP et d&rsquo;autres informations d&rsquo;utilisation sont automatiquement collect\u00e9es par un logiciel d&rsquo;analyse web, puis trait\u00e9es et \u00e9valu\u00e9es de mani\u00e8re anonyme. En utilisant notre pr\u00e9sence num\u00e9rique, vous acceptez la collecte, l&rsquo;utilisation et la divulgation de ces donn\u00e9es conform\u00e9ment \u00e0 la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n<h6>2.1 Enregistrement automatique<\/h6>\n<p>Le fournisseur d&rsquo;acc\u00e8s Internet des pages collecte et stocke automatiquement des informations dans des fichiers journaux de serveur, que votre navigateur nous transmet automatiquement. Celles-ci le sont:<\/p>\n<p>\u2022 Adresse IP<\/p>\n<p>\u2022 Type de navigateur et version du navigateur<\/p>\n<p>\u2022 Syst\u00e8me d&rsquo;exploitation utilis\u00e9<\/p>\n<p>\u2022 URL de r\u00e9f\u00e9rence<\/p>\n<p>\u2022 Nom d&rsquo;h\u00f4te de l&rsquo;ordinateur acc\u00e9dant<\/p>\n<p>\u2022 Heure de la requ\u00eate du serveur<\/p>\n<p>Ces donn\u00e9es ne peuvent pas \u00eatre directement affect\u00e9es \u00e0 des personnes sp\u00e9cifiques. Ces donn\u00e9es ne seront pas fusionn\u00e9es avec d&rsquo;autres sources de donn\u00e9es. Nous nous r\u00e9servons le droit de v\u00e9rifier ult\u00e9rieurement ces donn\u00e9es si nous avons connaissance d&rsquo;indications concr\u00e8tes d&rsquo;utilisation ill\u00e9gale.<\/p>\n<p>Ces donn\u00e9es et toutes les donn\u00e9es de ce site Internet sont enregistr\u00e9es par notre fournisseur d&rsquo;acc\u00e8s Internet Infomaniak SA, Quai du Mont-Blanc 33, 1201 Gen\u00e8ve, dont la d\u00e9claration de protection des donn\u00e9es <a href=\"https:\/\/www.infomaniak.com\/fr\/cgv\/politique-de-confidentialite\" target=\"_blank\" rel=\"noopener\">se trouve ici<\/a>.<\/p>\n<h5>3. Cookies<\/h5>\n<p>Certaines pages Internet utilisent des cookies. Les cookies n&rsquo;endommagent pas votre ordinateur et ne contiennent pas de virus. Les cookies servent \u00e0 rendre notre offre plus conviviale, plus efficace et plus s\u00fbre. Les cookies sont de petits fichiers texte qui sont stock\u00e9s sur votre ordinateur par votre navigateur.<\/p>\n<p>La plupart des cookies que nous utilisons sont des \u00ab\u00a0cookies temporaires\u00a0\u00bb. Ils sont automatiquement supprim\u00e9s \u00e0 la fin de votre visite. D&rsquo;autres cookies restent stock\u00e9s sur votre appareil jusqu&rsquo;\u00e0 ce que vous les supprimiez. Ces cookies nous permettent de reconna\u00eetre votre navigateur lors de votre prochaine visite.<\/p>\n<p>Vous pouvez param\u00e9trer votre navigateur de mani\u00e8re \u00e0 \u00eatre inform\u00e9 de la configuration des cookies et n&rsquo;autoriser les cookies que dans des cas individuels, accepter les cookies dans certains cas ou les exclure de mani\u00e8re g\u00e9n\u00e9rale et activer la suppression automatique des cookies \u00e0 la fermeture du navigateur. <strong>Si les cookies sont d\u00e9sactiv\u00e9s, la fonctionnalit\u00e9 de ce site Web peut \u00eatre limit\u00e9e.<\/strong><\/p>\n<h6>3.1 Comment peut-on emp\u00eacher l\u2019utilisation de cookies et d\u2019outils d\u2019analyse web?<\/h6>\n<p>La plupart des navigateurs acceptent les cookies automatiquement. Vous pouvez toutefois d\u00e9finir dans votre navigateur que vous n&rsquo;acceptez pas les cookies ou qu&rsquo;il vous demande votre accord avant d&rsquo;accepter un cookie d&rsquo;un site Internet que vous visitez. Vous pouvez aussi supprimer les cookies de votre ordinateur ou terminal mobile en utilisant la fonction correspondante de votre navigateur.<\/p>\n<p>Voici comment activer ou d\u00e9sactiver des cookies dans votre navigateur:<\/p>\n<p>V\u00e9rifiez quel est le navigateur que vous utilisez, puis s\u00e9lectionnez le lien correspondant ci-apr\u00e8s. Sur la page cible, vous trouverez les instructions sp\u00e9cifiques \u00e0 votre navigateur vous permettant d&rsquo;activer ou de d\u00e9sactiver les cookies.<\/p>\n<p><a href=\"https:\/\/support.google.com\/accounts\/answer\/61416?hl=fr\" target=\"_blank\" rel=\"noopener\">\u2022 Google Chrome<\/a><\/p>\n<p><a href=\"https:\/\/support.mozilla.org\/fr\/kb\/activer-desactiver-cookies-preferences\" target=\"_blank\" rel=\"noopener\">\u2022 Firefox<\/a><\/p>\n<p><a href=\"https:\/\/support.microsoft.com\/fr-ch\/help\/17442\/windows-internet-explorer-delete-manage-cookies\" target=\"_blank\" rel=\"noopener\">\u2022 Internet Explorer<\/a><\/p>\n<p><a href=\"https:\/\/support.apple.com\/fr-fr\/guide\/safari\/sfri11471\/mac\" target=\"_blank\" rel=\"noopener\">\u2022 Safari<\/a><\/p>\n<p>Si vous d\u00e9cidez de ne pas accepter nos cookies vous ne verrez pas s&rsquo;afficher certaines informations ni ne pourrez utiliser certaines fonctions destin\u00e9es \u00e0 am\u00e9liorer votre visite sur nos site Internet.<\/p>\n<p>Vous trouverez des informations compl\u00e9mentaires sur l&rsquo;utilisation des cookies sur le site Internet ci-apr\u00e8s: <a href=\"http:\/\/www.allaboutcookies.org\/fr\/\" target=\"_blank\" rel=\"noopener\">www.allaboutcookies.org<\/a><\/p>\n<h5>4. Cryptage SSL<\/h5>\n<p>Ce site utilise le cryptage SSL pour des raisons de s\u00e9curit\u00e9 et pour prot\u00e9ger la transmission de contenu confidentiel, comme les demandes que vous nous envoyez en tant qu&rsquo;exploitant du site.<\/p>\n<p>Vous reconnaissez une connexion crypt\u00e9e au fait que la ligne d&rsquo;adresse du navigateur passe de \u00ab\u00a0http:\/\/\u00a0\u00bb \u00e0 \u00ab\u00a0http<span style=\"color: #cc0000;\"><strong>s<\/strong><\/span>:\/\/\u00a0\u00bb <strong>et au symbole du cadenas sur la ligne de votre navigateur.\u00a0<\/strong><\/p>\n<p>Si le cryptage SSL est activ\u00e9, les donn\u00e9es que vous nous transmettez ne peuvent pas \u00eatre lues par des tiers.<\/p>\n<h5>5. Formulaire de contact<\/h5>\n<p>Si vous nous envoyez des demandes de renseignements \u00e0 l&rsquo;aide du formulaire de contact, nous conservons vos coordonn\u00e9es, y compris les donn\u00e9es de contact que vous avez saisies, y compris votre adresse IP, pour le traitement de la demande et en cas de questions compl\u00e9mentaires. Nous ne transmettons pas ces donn\u00e9es sans votre consentement.<\/p>\n<h5>6. Fonction de commentaire<\/h5>\n<p>Pour la fonction de commentaire sur cette page, en plus de votre commentaire, les informations au moment de la cr\u00e9ation du commentaire, votre adresse e-mail et, si vous ne postez pas anonymement, le nom d&rsquo;utilisateur que vous avez choisi seront enregistr\u00e9s.<\/p>\n<h6>6.1 Stockage de l&rsquo;adresse IP<\/h6>\n<p>Notre fonction de commentaire stocke les adresses IP des utilisateurs qui publient des commentaires. Puisque nous v\u00e9rifions les commentaires sur notre site avant de les activer, nous avons besoin de ces donn\u00e9es afin de pouvoir prendre des mesures contre l&rsquo;auteur en cas d&rsquo;infractions telles que des insultes ou de la propagande.<\/p>\n<h5>7. Donn\u00e9es de la newsletter<\/h5>\n<p>Si vous souhaitez recevoir la newsletter propos\u00e9e sur le site, nous avons besoin d&rsquo;une adresse e-mail de votre part ainsi que d&rsquo;informations nous permettant de v\u00e9rifier que vous \u00eates le propri\u00e9taire de l&rsquo;adresse e-mail fournie et que vous acceptez de recevoir la newsletter.<\/p>\n<p>Nous utilisons ces donn\u00e9es exclusivement pour l&rsquo;envoi des informations demand\u00e9es.<\/p>\n<p>Vous pouvez \u00e0 tout moment r\u00e9voquer votre consentement \u00e0 l&rsquo;enregistrement des donn\u00e9es, de l&rsquo;adresse e-mail et de leur utilisation pour l&rsquo;envoi de la newsletter, par exemple via le lien \u00ab\u00a0se d\u00e9sinscrire\u00a0\u00bb de la newsletter.<\/p>\n<p>L&rsquo;inscription \u00e0 notre newsletter s&rsquo;effectue dans le cadre d&rsquo;une proc\u00e9dure dite Double-Opt-In. Cela signifie que vous recevrez un e-mail apr\u00e8s l&rsquo;inscription vous demandant de confirmer votre inscription. Cette confirmation est n\u00e9cessaire pour que personne ne puisse s&rsquo;inscrire avec des adresses e-mail externes.<\/p>\n<p>Les inscriptions \u00e0 la newsletter sont enregistr\u00e9es afin de pouvoir prouver le processus d&rsquo;inscription conform\u00e9ment aux exigences l\u00e9gales. Cela inclut le stockage des temps de connexion et de confirmation ainsi que de l&rsquo;adresse IP. De m\u00eame, les modifications de vos donn\u00e9es stock\u00e9es avec MailChimp sont enregistr\u00e9es.<\/p>\n<h6>7.1 MailChimp<\/h6>\n<p>La newsletter est envoy\u00e9e via \u00ab\u00a0MailChimp\u00a0\u00bb, une plateforme de distribution de newsletter du fournisseur am\u00e9ricain Rocket Science Group, LLC, 675 Ponce De Leon Ave NE #5000, Atlanta, GA 30308, USA.<\/p>\n<p>Les adresses e-mail des destinataires de notre newsletter, ainsi que leurs autres donn\u00e9es d\u00e9crites dans le cadre de cette notice, sont stock\u00e9es sur les serveurs de MailChimp aux Etats-Unis. MailChimp utilise ces informations pour envoyer et \u00e9valuer le bulletin en notre nom. En outre, MailChimp peut utiliser ces donn\u00e9es selon ses propres informations pour l&rsquo;optimisation ou l&rsquo;am\u00e9lioration de ses propres services, par exemple pour l&rsquo;optimisation technique de l&rsquo;envoi et de l&rsquo;affichage de la newsletter ou \u00e0 des fins \u00e9conomiques, pour d\u00e9terminer de quels pays les destinataires proviennent. MailChimp n&rsquo;utilise cependant pas les donn\u00e9es de nos destinataires pour leur \u00e9crire ou les transmettre \u00e0 des tiers.<\/p>\n<p>Nous comptons sur la fiabilit\u00e9 et la s\u00e9curit\u00e9 informatique et de donn\u00e9es de MailChimp. MailChimp est certifi\u00e9 selon l&rsquo;accord de protection des donn\u00e9es \u00ab\u00a0Privacy Shield\u00a0\u00bb entre les Etats-Unis et l&rsquo;UE et s&rsquo;engage donc \u00e0 respecter les r\u00e9glementations europ\u00e9ennes en mati\u00e8re de protection des donn\u00e9es.<\/p>\n<p>Vous pouvez consulter la politique de confidentialit\u00e9 de MailChimp <a href=\"https:\/\/mailchimp.com\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/p>\n<h6>7.2 R\u00e9siliation\/r\u00e9vocation<\/h6>\n<p>Vous pouvez \u00e0 tout moment annuler la r\u00e9ception de notre newsletter, c&rsquo;est-\u00e0-dire r\u00e9voquer votre consentement. En m\u00eame temps, vous consentez \u00e0 son envoi via MailChimp et les analyses statistiques expirent.<\/p>\n<p>Vous trouverez un lien pour annuler la newsletter \u00e0 la fin de chaque newsletter.<\/p>\n<h5>8.\u00a0Base juridique le r\u00e8glement sur la protection des donn\u00e9es (RGPD)<\/h5>\n<p>Conform\u00e9ment aux dispositions de r\u00e8glement sur la protection des donn\u00e9es (RGPD)\u00a0entr\u00e9e en vigueur le 25 mai 2018, nous vous informons que votre consentement \u00e0 l&rsquo;envoi d&rsquo;adresses e-mail est bas\u00e9 sur l&rsquo;art. 6 al. 1 let. a, 7 RGPD et \u00a7 7 al. 2 no. 3 ou 3 UWG. L&rsquo;utilisation du prestataire de services d&rsquo;exp\u00e9dition MailChimp, la r\u00e9alisation d&rsquo;enqu\u00eates et d&rsquo;analyses statistiques ainsi que l&rsquo;enregistrement de la proc\u00e9dure d&rsquo;enregistrement sont effectu\u00e9s sur la base de nos int\u00e9r\u00eats l\u00e9gitimes au sens de l&rsquo;art. 6, al. 1, let. f, RGPD. Nous sommes int\u00e9ress\u00e9s \u00e0 utiliser un syst\u00e8me de newsletter convivial et s\u00e9curis\u00e9 qui r\u00e9pond \u00e0 la fois \u00e0 nos int\u00e9r\u00eats commerciaux et aux attentes des utilisateurs.<\/p>\n<h6>8.1\u00a0Modification de la d\u00e9claration de confidentialit\u00e9<\/h6>\n<p>De temps \u00e0 autre, il peut \u00eatre n\u00e9cessaire de modifier la pr\u00e9sente d\u00e9claration de confidentialit\u00e9, par exemple en raison de l&rsquo;\u00e9volution de notre pr\u00e9sence num\u00e9rique ou en cas de modifications l\u00e9gales. SOS-Massage se r\u00e9serve donc le droit de modifier \u00e0 tout moment la d\u00e9claration de confidentialit\u00e9 avec effet \u00e0 une date ult\u00e9rieure.<\/p>\n<h5>9. Services d&rsquo;analyse Internet<\/h5>\n<p>Ce site Web utilise les fonctions du service d&rsquo;analyse Web Google Analytics. Le fournisseur est Google Inc, 1600 Amphitheatre Parkway Parkway Mountain View, CA 94043, USA.<\/p>\n<p>Les services d\u2019analyse du r\u00e9seau utilisent des cookies (cf. par. 3) qui \u00e9valuent l\u2019utilisation de la pr\u00e9sence num\u00e9rique, pour obtenir des informations en vue de l\u2019am\u00e9lioration de nos prestations, ainsi que pour effectuer une analyse statistique de la fr\u00e9quentation de nos sites. Tout rapprochement avec des personnes en particulier est impossible. Les informations alors g\u00e9n\u00e9r\u00e9es peuvent \u00eatre transf\u00e9r\u00e9es \u00e0 un serveur situ\u00e9 \u00e0 l\u2019\u00e9tranger et y \u00eatre enregistr\u00e9es. Vous pouvez emp\u00eacher l\u2019enregistrement des cookies en modifiant en cons\u00e9quence les param\u00e8tres de votre navigateur (cf. par. 3.1).<\/p>\n<h5>10.\u00a0Droit \u00e0 l&rsquo;information, \u00e0 la suppression et au blocage<\/h5>\n<p>Vous avez \u00e0 tout moment le droit d&rsquo;obtenir gratuitement des informations sur vos donn\u00e9es personnelles stock\u00e9es, leur origine, leur destinataire et la finalit\u00e9 du traitement des donn\u00e9es, ainsi qu&rsquo;un droit de rectification, de blocage ou de suppression de ces donn\u00e9es. Vous pouvez nous contacter par \u00e9crit avec une copie de votre passeport ou de votre carte d\u2019identit\u00e9 \u00e0 l&rsquo;adresse indiqu\u00e9e dans l&rsquo;impressum pour cette question et d&rsquo;autres questions sur le sujet des donn\u00e9es personnelles. Si la suppression de ces donn\u00e9es n&rsquo;est pas autoris\u00e9e pour des raisons l\u00e9gales, les donn\u00e9es seront bloqu\u00e9es au lieu d&rsquo;\u00eatre supprim\u00e9es.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. Protection des donn\u00e9es Nous accordons une grande importance \u00e0 la protection de vos donn\u00e9es personnelles. Nous les traitons donc avec le plus grand soin, conform\u00e9ment aux dispositions l\u00e9gales en vigueur relatives \u00e0 la protection des donn\u00e9es et \u00e0 la d\u00e9claration de confidentialit\u00e9. Dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9, nous vous informons sur nos m\u00e9thodes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":92,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"IMPRESSUM\r\n\r\n\r\nKONTAKTADRESSE\r\n\r\nSOS Massage\r\nPascal Goetz\r\n20, Chemin de la Petite-Boiss\u00e8re\r\nCH-1208 Gen\u00e8ve\r\nTel.: +41 79 566 61 73\r\nE-Mail: welcome@sos-massage.ch\r\nwww.sos-massage.ch\r\n\r\n\r\nZAHLSTELLENREGISTRIER-NUMMER - ZSR \r\n\r\nASCA - ZSR R876962\r\nEMR\/RME - ZSR W878862 \r\n\r\n\r\nREGISTRIERUNG-NUMMER ASCA, EMR\r\n\r\nASCA - Schweizerische Stiftung f\u00fcr Komplement\u00e4rmedizin Nr. 98649\r\nEMR -  Erfahrungsmedizinisches Register Nr. 32273\r\n\r\n\r\nREGISTRIERUNG SERVICE M\u00c9DECIN CANTONAL GEN\u00c8VE\r\n\r\nUnser Angebot ist im kantonalen Register f\u00fcr komplement\u00e4re Methoden regis-triert: Nr.\/Ref. Pr-040780\r\n\r\n\r\nRECHTLICHE HINWEISE\r\n\r\nHAFTUNGS- UND GEW\u00c4HRLEISTUNGSAUSCHLUSS\r\n\r\nHinsichtlich der inhaltlichen Richtigkeit, Genauigkeit, Aktualit\u00e4t, Zuverl\u00e4ssigkeit und Vollst\u00e4ndigkeit der Informationen \u00fcbernimmt der Autor keine Gew\u00e4hrleis-tung. Haftungsanspr\u00fcche wegen Sch\u00e4den jeglicher Art, welche aus dem Zu-griff oder der Nutzung bzw. Nichtnutzung der ver\u00f6ffentlichten Informationen, durch Missbrauch der Verbindung oder durch technische St\u00f6rungen entstan-den sind, werden ausgeschlossen.\r\n\r\nAllf\u00e4llige medizinische Ratschl\u00e4ge sind nach bestem Wissen und Gewissen zu-sammengestellt, ersetzen jedoch keinesfalls einen Arztbesuch und werden auf eigenes Risiko befolgt. \r\n\r\nAlle Angebote sind unverbindlich. Der Autor beh\u00e4lt sich das Recht vor, jeder-zeit Inhalte dieser Webseite ohne Ank\u00fcndigung zu ver\u00e4ndern, zu erg\u00e4nzen, zu l\u00f6schen oder die Ver\u00f6ffentlichung zeitweise oder endg\u00fcltig einzustellen.\r\n\r\n\r\nHAFTUNGSAUSCHLUSS F\u00dcR VERWEISE UND LINKS\r\n\r\nVerweise und Links auf Webseiten Dritter liegen ausserhalb unseres Verantwor-tungsbereiches. Es wird jegliche Verantwortung und Haftung f\u00fcr solche Web-seiten abgelehnt. Der Zugriff und die Nutzung solcher Webseiten erfolgen auf eigene Gefahr der Nutzerin oder des Nutzers. \r\n\r\n \r\n\r\nURHEBERRECHTE\r\n\r\nDie Urheber- und alle anderen Rechte an Inhalten, Bildern, Fotos oder ande-ren Dateien auf dieser Webseite geh\u00f6ren ausschliesslich den Autoren von sos-massage.ch. F\u00fcr die Reproduktion jeglicher Elemente ist die schriftliche Zu-stimmung der Autoren im Voraus einzuholen. \r\n\r\nDATENSCHUTZ\r\n\r\nGest\u00fctzt auf den Artikel 13 der schweizerischen Bundesverfassung und die da-tenschutzrechtlichen Bestimmungen des Bundes (Datenschutzgesetz, DSG) hat jede Person Anspruch auf Schutz ihrer Privatsph\u00e4re sowie auf Schutz vor Missbrauch ihrer pers\u00f6nlichen Daten. Wir halten diese Bestimmungen ein. Per-s\u00f6nliche Daten werden streng vertraulich behandelt und weder an Dritte ver-kauft noch weiter gegeben. In enger Zusammenarbeit mit unserem Hosting-Provider bem\u00fchen wir uns, die Datenbanken so gut wie m\u00f6glich vor fremden Zugriffen, Verlusten, Missbrauch oder vor F\u00e4lschung zu sch\u00fctzen. Beim Zugriff aus unsere Webseiten werden folgende Daten in Logfiles gespeichert: IP-Adresse, Datum, Uhrzeit, Browser-Anfrage und allg. \u00fcbertragene Informatio-nen zum Betriebssystem resp. Browser. Diese Nutzungsdaten bilden die Basis f\u00fcr statistische, anonyme Auswertungen, so dass Trends erkennbar sind, an-hand derer wir unsere Angebote entsprechend verbessern k\u00f6nnen.\r\n\r\n\r\nDATENSCHUTZ \u2013 GOOGLE ANALYTICS\r\n\r\nDiese Webseite benutzt Google Analytics, einen Webanalysedienst der Google Inc. Google Analytics verwendet sog. Cookies, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Webseite durch Sie erm\u00f6glicht. Die durch den Cookie erzeugten Informatio-nen \u00fcber Ihre Benutzung dieser Webseite, einschliesslich Ihrer IP-Adresse, wird an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Google wird diese Informationen benutzen, um Ihre Nutzung der Webseite auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten f\u00fcr die Websitebetreiber zusammenzustellen und um weitere mit der Websitenutzung und der Internet-nutzung verbundene Dienstleistungen zu erbringen. Auch wird Google diese Informationen gegebenenfalls an Dritte \u00fcbertragen, sofern dies gesetzlich vorgeschrieben oder soweit Dritte diese Daten im Auftrag von Google verar-beiten. Google wird in keinem Fall Ihre IP-Adresse mit anderen Daten von Google in Verbindung bringen. Sie k\u00f6nnen die Installation der Cookies durch eine entsprechende Einstellung in Ihrer Browser Software verhindern. Gege-benenfalls k\u00f6nnen Sie damit nicht s\u00e4mtliche Funktionen dieser Webseite voll umf\u00e4nglich nutzen. Durch die Nutzung dieser Webseite erkl\u00e4ren Sie sich mit der Bearbeitung der \u00fcber Sie erhobenen Daten durch Google in der zuvor beschriebenen Art und Weise und zu dem zuvor benannten Zweck einver-standen.    \r\n\r\n\r\nREALISIERUNG, PROGRAMMIERUNG\r\n\r\nSOS Massage.ch, Webanwendung WordPress","_et_gb_content_width":"","footnotes":""},"class_list":["post-6606","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protection des donn\u00e9es et informations l\u00e9gales - SOS-Massage FR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protection des donn\u00e9es et informations l\u00e9gales - SOS-Massage FR\" \/>\n<meta property=\"og:description\" content=\"1. Protection des donn\u00e9es Nous accordons une grande importance \u00e0 la protection de vos donn\u00e9es personnelles. Nous les traitons donc avec le plus grand soin, conform\u00e9ment aux dispositions l\u00e9gales en vigueur relatives \u00e0 la protection des donn\u00e9es et \u00e0 la d\u00e9claration de confidentialit\u00e9. Dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9, nous vous informons sur nos m\u00e9thodes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/\" \/>\n<meta property=\"og:site_name\" content=\"SOS-Massage FR\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-10T16:53:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/impresum-2\\\/\",\"url\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/impresum-2\\\/\",\"name\":\"Protection des donn\u00e9es et informations l\u00e9gales - SOS-Massage FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/#website\"},\"datePublished\":\"2018-10-25T16:25:43+00:00\",\"dateModified\":\"2018-11-10T16:53:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/impresum-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/impresum-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/impresum-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protection des donn\u00e9es et informations l\u00e9gales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/\",\"name\":\"SOS-Massage FR\",\"description\":\"flexibilit\u00e9 maximale, th\u00e9rapie efficace, reconnu par les caisses maladie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sos-massage.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protection des donn\u00e9es et informations l\u00e9gales - SOS-Massage FR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Protection des donn\u00e9es et informations l\u00e9gales - SOS-Massage FR","og_description":"1. Protection des donn\u00e9es Nous accordons une grande importance \u00e0 la protection de vos donn\u00e9es personnelles. Nous les traitons donc avec le plus grand soin, conform\u00e9ment aux dispositions l\u00e9gales en vigueur relatives \u00e0 la protection des donn\u00e9es et \u00e0 la d\u00e9claration de confidentialit\u00e9. Dans la pr\u00e9sente d\u00e9claration de confidentialit\u00e9, nous vous informons sur nos m\u00e9thodes [&hellip;]","og_url":"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/","og_site_name":"SOS-Massage FR","article_modified_time":"2018-11-10T16:53:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/","url":"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/","name":"Protection des donn\u00e9es et informations l\u00e9gales - SOS-Massage FR","isPartOf":{"@id":"https:\/\/www.sos-massage.ch\/fr\/#website"},"datePublished":"2018-10-25T16:25:43+00:00","dateModified":"2018-11-10T16:53:37+00:00","breadcrumb":{"@id":"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sos-massage.ch\/fr\/impresum-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sos-massage.ch\/fr\/impresum-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sos-massage.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Protection des donn\u00e9es et informations l\u00e9gales"}]},{"@type":"WebSite","@id":"https:\/\/www.sos-massage.ch\/fr\/#website","url":"https:\/\/www.sos-massage.ch\/fr\/","name":"SOS-Massage FR","description":"flexibilit\u00e9 maximale, th\u00e9rapie efficace, reconnu par les caisses maladie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sos-massage.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.sos-massage.ch\/fr\/wp-json\/wp\/v2\/pages\/6606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sos-massage.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sos-massage.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sos-massage.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sos-massage.ch\/fr\/wp-json\/wp\/v2\/comments?post=6606"}],"version-history":[{"count":5,"href":"https:\/\/www.sos-massage.ch\/fr\/wp-json\/wp\/v2\/pages\/6606\/revisions"}],"predecessor-version":[{"id":6667,"href":"https:\/\/www.sos-massage.ch\/fr\/wp-json\/wp\/v2\/pages\/6606\/revisions\/6667"}],"wp:attachment":[{"href":"https:\/\/www.sos-massage.ch\/fr\/wp-json\/wp\/v2\/media?parent=6606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}